{"id":10335,"date":"2024-12-10T17:24:15","date_gmt":"2024-12-10T16:24:15","guid":{"rendered":"https:\/\/snowdance.net\/electro-party\/"},"modified":"2025-01-08T13:57:36","modified_gmt":"2025-01-08T12:57:36","slug":"electro-party","status":"publish","type":"post","link":"https:\/\/snowdance.net\/en\/electro-party\/","title":{"rendered":"Electro Party"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>The scene insiders from Essen diese and Statik (organizer) celebrate together with the Snowdancers again. This time in the Marktkirche in the center of Essen.<\/p>\n<p>From 22:00, DJ La Frise and other well-known DJs will be playing their extremely danceable electro sound. It is certain that the crew will transform the medieval church into a magical place with their lighting concept.<\/p>\n<p>Due to limited space, we kindly ask you to use the advance booking system.<\/p>\n<p><b>Please note: Permanent tickets for the film festival are not valid for this party.<\/b><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;6px&#8221; column_border_color=&#8221;#494431&#8243; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<p style=\"text-align: left;\">Saturday, 01.02.2025, from 22:00<br \/>\nMarktkirche Essen, Markt 2, 45127 Essen<br \/>\nAdmission: 16,95 euros<br \/>\n<a href=\"https:\/\/de.ra.co\/events\/2064344\" target=\"_blank\" rel=\"noopener\">Buy ticket<\/a><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#494431&#8243; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;10347&#8243; image_size=&#8221;portfolio-thumb&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;5114&#8243; image_size=&#8221;portfolio-thumb&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;10350&#8243; image_size=&#8221;portfolio-thumb&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>01.02.2025 \u2013 22:00 \u2013 Marktkirche &#8230; more info \u2192<\/p>\n","protected":false},"author":3,"featured_media":10333,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"class_list":["post-10335","post","type-post","status-publish","format-standard","has-post-thumbnail","category-events-en-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Electro Party &#8211; Snowdance Independent Film Festival<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snowdance.net\/en\/electro-party\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Electro Party &#8211; Snowdance Independent Film Festival\" \/>\n<meta property=\"og:description\" content=\"01.02.2025 \u2013 22:00 \u2013 Marktkirche ... more info \u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snowdance.net\/en\/electro-party\/\" \/>\n<meta property=\"og:site_name\" content=\"Snowdance Independent Film Festival\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Snowdance.Filmfestival.Landsberg\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-10T16:24:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-08T12:57:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/snowdance.net\/wp-content\/uploads\/2024\/12\/Party.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1386\" \/>\n\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pascal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"pascal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/\"},\"author\":{\"name\":\"pascal\",\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/#\\\/schema\\\/person\\\/35a39adcb1d0654720c784c295d8b33a\"},\"headline\":\"Electro Party\",\"datePublished\":\"2024-12-10T16:24:15+00:00\",\"dateModified\":\"2025-01-08T12:57:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/\"},\"wordCount\":1155,\"publisher\":{\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/snowdance.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Party.jpg\",\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/\",\"url\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/\",\"name\":\"Electro Party &#8211; Snowdance Independent Film Festival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/snowdance.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Party.jpg\",\"datePublished\":\"2024-12-10T16:24:15+00:00\",\"dateModified\":\"2025-01-08T12:57:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/#primaryimage\",\"url\":\"https:\\\/\\\/snowdance.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Party.jpg\",\"contentUrl\":\"https:\\\/\\\/snowdance.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Party.jpg\",\"width\":1386,\"height\":924},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/electro-party\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/snowdance.net\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Electro Party\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/snowdance.net\\\/en\\\/\",\"name\":\"Snowdance Independent Film Festival\",\"description\":\"Independent Film Festival in Essen\",\"publisher\":{\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/snowdance.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/#organization\",\"name\":\"Indie-Stars UG\",\"url\":\"https:\\\/\\\/snowdance.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/snowdance.net\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/snowdance_logo-hor_gold.png\",\"contentUrl\":\"https:\\\/\\\/snowdance.net\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/snowdance_logo-hor_gold.png\",\"width\":1000,\"height\":153,\"caption\":\"Indie-Stars UG\"},\"image\":{\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Snowdance.Filmfestival.Landsberg\\\/\",\"https:\\\/\\\/www.instagram.com\\\/snowdancefestival\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/snowdance.net\\\/en\\\/#\\\/schema\\\/person\\\/35a39adcb1d0654720c784c295d8b33a\",\"name\":\"pascal\",\"url\":\"https:\\\/\\\/snowdance.net\\\/en\\\/author\\\/pascal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Electro Party &#8211; Snowdance Independent Film Festival","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snowdance.net\/en\/electro-party\/","og_locale":"en_US","og_type":"article","og_title":"Electro Party &#8211; Snowdance Independent Film Festival","og_description":"01.02.2025 \u2013 22:00 \u2013 Marktkirche ... more info \u2192","og_url":"https:\/\/snowdance.net\/en\/electro-party\/","og_site_name":"Snowdance Independent Film Festival","article_publisher":"https:\/\/www.facebook.com\/Snowdance.Filmfestival.Landsberg\/","article_published_time":"2024-12-10T16:24:15+00:00","article_modified_time":"2025-01-08T12:57:36+00:00","og_image":[{"width":1386,"height":924,"url":"https:\/\/snowdance.net\/wp-content\/uploads\/2024\/12\/Party.jpg","type":"image\/jpeg"}],"author":"pascal","twitter_card":"summary_large_image","twitter_misc":{"Written by":"pascal","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/snowdance.net\/en\/electro-party\/#article","isPartOf":{"@id":"https:\/\/snowdance.net\/en\/electro-party\/"},"author":{"name":"pascal","@id":"https:\/\/snowdance.net\/en\/#\/schema\/person\/35a39adcb1d0654720c784c295d8b33a"},"headline":"Electro Party","datePublished":"2024-12-10T16:24:15+00:00","dateModified":"2025-01-08T12:57:36+00:00","mainEntityOfPage":{"@id":"https:\/\/snowdance.net\/en\/electro-party\/"},"wordCount":1155,"publisher":{"@id":"https:\/\/snowdance.net\/en\/#organization"},"image":{"@id":"https:\/\/snowdance.net\/en\/electro-party\/#primaryimage"},"thumbnailUrl":"https:\/\/snowdance.net\/wp-content\/uploads\/2024\/12\/Party.jpg","articleSection":["Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/snowdance.net\/en\/electro-party\/","url":"https:\/\/snowdance.net\/en\/electro-party\/","name":"Electro Party &#8211; Snowdance Independent Film Festival","isPartOf":{"@id":"https:\/\/snowdance.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snowdance.net\/en\/electro-party\/#primaryimage"},"image":{"@id":"https:\/\/snowdance.net\/en\/electro-party\/#primaryimage"},"thumbnailUrl":"https:\/\/snowdance.net\/wp-content\/uploads\/2024\/12\/Party.jpg","datePublished":"2024-12-10T16:24:15+00:00","dateModified":"2025-01-08T12:57:36+00:00","breadcrumb":{"@id":"https:\/\/snowdance.net\/en\/electro-party\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snowdance.net\/en\/electro-party\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/snowdance.net\/en\/electro-party\/#primaryimage","url":"https:\/\/snowdance.net\/wp-content\/uploads\/2024\/12\/Party.jpg","contentUrl":"https:\/\/snowdance.net\/wp-content\/uploads\/2024\/12\/Party.jpg","width":1386,"height":924},{"@type":"BreadcrumbList","@id":"https:\/\/snowdance.net\/en\/electro-party\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/snowdance.net\/en\/"},{"@type":"ListItem","position":2,"name":"Electro Party"}]},{"@type":"WebSite","@id":"https:\/\/snowdance.net\/en\/#website","url":"https:\/\/snowdance.net\/en\/","name":"Snowdance Independent Film Festival","description":"Independent Film Festival in Essen","publisher":{"@id":"https:\/\/snowdance.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snowdance.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/snowdance.net\/en\/#organization","name":"Indie-Stars UG","url":"https:\/\/snowdance.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/snowdance.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/snowdance.net\/wp-content\/uploads\/2022\/10\/snowdance_logo-hor_gold.png","contentUrl":"https:\/\/snowdance.net\/wp-content\/uploads\/2022\/10\/snowdance_logo-hor_gold.png","width":1000,"height":153,"caption":"Indie-Stars UG"},"image":{"@id":"https:\/\/snowdance.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Snowdance.Filmfestival.Landsberg\/","https:\/\/www.instagram.com\/snowdancefestival\/"]},{"@type":"Person","@id":"https:\/\/snowdance.net\/en\/#\/schema\/person\/35a39adcb1d0654720c784c295d8b33a","name":"pascal","url":"https:\/\/snowdance.net\/en\/author\/pascal\/"}]}},"_links":{"self":[{"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/posts\/10335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/comments?post=10335"}],"version-history":[{"count":30,"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/posts\/10335\/revisions"}],"predecessor-version":[{"id":11611,"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/posts\/10335\/revisions\/11611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/media\/10333"}],"wp:attachment":[{"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/media?parent=10335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/categories?post=10335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snowdance.net\/en\/wp-json\/wp\/v2\/tags?post=10335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}